{"id":219,"count":3,"description":"","link":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/category\/national-security\/spies\/","name":"Spies","slug":"spies","taxonomy":"category","parent":218,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spies Archives - Steven C. Welsh - SCW SteveWire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stevencwelsh.info\/news\/stevewire\/category\/national-security\/spies\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.stevencwelsh.info\\\/news\\\/stevewire\\\/category\\\/national-security\\\/spies\\\/\",\"url\":\"https:\\\/\\\/www.stevencwelsh.info\\\/news\\\/stevewire\\\/category\\\/national-security\\\/spies\\\/\",\"name\":\"Spies Archives - Steven C. Welsh - SCW SteveWire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stevencwelsh.info\\\/news\\\/stevewire\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stevencwelsh.info\\\/news\\\/stevewire\\\/category\\\/national-security\\\/spies\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stevencwelsh.info\\\/news\\\/stevewire\\\/category\\\/national-security\\\/spies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.stevencwelsh.info\\\/news\\\/stevewire\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"National Security\",\"item\":\"https:\\\/\\\/www.stevencwelsh.info\\\/news\\\/stevewire\\\/category\\\/national-security\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Spies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stevencwelsh.info\\\/news\\\/stevewire\\\/#website\",\"url\":\"https:\\\/\\\/www.stevencwelsh.info\\\/news\\\/stevewire\\\/\",\"name\":\"Steven C. Welsh - SCW SteveWire\",\"description\":\"SCW Communications &amp; Analysis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stevencwelsh.info\\\/news\\\/stevewire\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spies Archives - Steven C. Welsh - SCW SteveWire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/category\/national-security\/spies\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/category\/national-security\/spies\/","url":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/category\/national-security\/spies\/","name":"Spies Archives - Steven C. Welsh - SCW SteveWire","isPartOf":{"@id":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/#website"},"breadcrumb":{"@id":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/category\/national-security\/spies\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/category\/national-security\/spies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/"},{"@type":"ListItem","position":2,"name":"National Security","item":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/category\/national-security\/"},{"@type":"ListItem","position":3,"name":"Spies"}]},{"@type":"WebSite","@id":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/#website","url":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/","name":"Steven C. Welsh - SCW SteveWire","description":"SCW Communications &amp; Analysis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/wp-json\/wp\/v2\/categories\/219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/wp-json\/wp\/v2\/categories\/218"}],"wp:post_type":[{"href":"https:\/\/www.stevencwelsh.info\/news\/stevewire\/wp-json\/wp\/v2\/posts?categories=219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}